{"id":48480,"date":"2026-03-29T03:56:47","date_gmt":"2026-03-29T03:56:47","guid":{"rendered":"http:\/\/vocesver.com\/noticias\/?p=48480"},"modified":"2026-03-29T03:57:15","modified_gmt":"2026-03-29T03:57:15","slug":"atiende-ayuntamiento-de-veracruz-reporte-de-canino-atacado-por-abejas","status":"publish","type":"post","link":"http:\/\/vocesver.com\/noticias\/atiende-ayuntamiento-de-veracruz-reporte-de-canino-atacado-por-abejas\/","title":{"rendered":"Atiende Ayuntamiento de Veracruz reporte de canino atacado por abejas."},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>Ausencio Rivera \/Vocesver. com\/noticias<\/p>\n\n\n\n<p>Veracruz, Ver. A 28 de Marzo 2026.&nbsp;<\/p>\n\n\n\n<p>Tras recibir una denuncia ciudadana, el Ayuntamiento de Veracruz atendi\u00f3 un incidente registrado en el fraccionamiento Casas D\u00edaz, en el que lamentablemente falleci\u00f3 un canino tras ser picado por abejas.&nbsp;<\/p>\n\n\n\n<p>Personal de la direcci\u00f3n de Salud y Protecci\u00f3n Animal, en coordinaci\u00f3n con la direcci\u00f3n de Protecci\u00f3n Civil y el Heroico Cuerpo de Bomberos, se trasladaron al sitio a atender el reporte hecho en redes sociales por vecinos que denunciaban la omisi\u00f3n de cuidados hacia el perro de raza Husky, mismo que, al ser revisado ya no presentaba signos vitales.&nbsp;<\/p>\n\n\n\n<p>Durante la inspecci\u00f3n, residentes de la zona se\u00f1alaron que el perro, identificado como \u00abTango Mateo\u00bb, presuntamente sufr\u00eda abandono y desnutrici\u00f3n previa al incidente; mientras elementos operativos y apicultores especializados trabajaron en el lugar para controlar el enjambre y garantizar la seguridad de las y los vecinos.<\/p>\n\n\n\n<p>Ante los testimonios y la evidencia recabada, las autoridades municipales dejaron un citatorio oficial al propietario para el esclarecimiento de los hechos y deslindar responsabilidades por presunta crueldad animal.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ausencio Rivera \/Vocesver. com\/noticias Veracruz, Ver. A 28 de Marzo 2026.&nbsp; Tras recibir una denuncia ciudadana, el Ayuntamiento de Veracruz<\/p>\n","protected":false},"author":2,"featured_media":48481,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[2],"tags":[],"class_list":["post-48480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infogral"],"_links":{"self":[{"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/posts\/48480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/comments?post=48480"}],"version-history":[{"count":1,"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/posts\/48480\/revisions"}],"predecessor-version":[{"id":48482,"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/posts\/48480\/revisions\/48482"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/media\/48481"}],"wp:attachment":[{"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/media?parent=48480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/categories?post=48480"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/tags?post=48480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}