{"id":40182,"date":"2023-07-29T23:29:23","date_gmt":"2023-07-29T23:29:23","guid":{"rendered":"http:\/\/vocesver.com\/noticias\/?p=40182"},"modified":"2023-07-29T23:36:29","modified_gmt":"2023-07-29T23:36:29","slug":"discapacitados-rrquieren-de-ayuda-de-los-tres-niveles-de-gobiernoayala-fararoni","status":"publish","type":"post","link":"http:\/\/vocesver.com\/noticias\/discapacitados-rrquieren-de-ayuda-de-los-tres-niveles-de-gobiernoayala-fararoni\/","title":{"rendered":"DISCAPACITADOS REQUIEREN DE AYUDA DE LOS TRES NIVELES DE GOBIERNO:AYALA FARARONI."},"content":{"rendered":"\n<p>AUSENCIO RIVERA\/VOCESVER.COM\/NOTICIAS<br>Veracruz,Ver,. a  29 de Julio 2023.-El presidente de la Casa del del Discapacitado  Veracruzano A.C Ignacio Ayala Fararoni manifest\u00f3 lo urgente necesidad de los tres niveles de gobierno(Federal,Estatal y Municipal)para atender a las personas con discapacidad que existen toda la entidad veracruzana y que son muchos.<br>Es necesario que estos gobiernos volteen a ver a este sector ya que hoy m\u00e1s que nunca necesitan de ellos, sobretodo las personas con discapacidad mental e intelectual \u00abporque somos much\u00edsimos\u00bb.<br>Al se\u00f1alar que adem\u00e1s de discapacitado \u00e9l es  bipolar desde hace muchos a\u00f1os,el entrevistado dijo: nosotros tenemos muchas discapacidades mentales y por lo mismo es urgente que todos los gobiernos nos ayuden.<br>Al reiterar que este llamado es para los gobiernos federal,estatal y  municipal, el declarante reconoci\u00f3 que las necesidades de este sector siguen siendo muy grandes.<\/p>\n\n\n\n<p>QUIEREN QUE UNA MUJER SEA LA <\/p>\n\n\n\n<p>PR\u00d3XIMA GOBERNADORA DE VERCRZ.<br>Por otro lado el representante de los discapacitados se pronunci\u00f3 porque la alcaldesa del Puerto de  Veracruz Patricia Lobeira de Yunes sea la pr\u00f3xima candidata a la Gubernatura del Estado de Veracruz.<br>\u00abNosotros consideramos que ya es tiempo que haya mujeres en todos los cargos p\u00fablicos y  que todos los hombres  renuncien para que \u00e9stas ocupen sus puestos\u00bb.<br>En el caso de la Alcaldesa dijo que ellos la apoyan porque es la \u00fanica que est\u00e1 apoyando al sector de los discapacitados.<\/p>\n\n\n\n<p> Con la Presidenta Municipal hemos tenido buen apoyo y nosotros como luchadores sociales estamos a favor de todo lo bueno y rechazamos todo lo malo.<br>El entrevistado destac\u00f3 que actualmente existen m\u00e1s de un mill\u00f3n y medio de discapacitados en el Estado de Veracruz y todos ellos requieren del apoyo de las autoridades.  <\/p>\n\n\n\n<p>Actualmente la principal demandas de estos es que los ayuden con una credencial digital que los identifique en su celular ya que actualmente ese tipo de credencial no existe en la Rep\u00fablica Mexicana y consideran que es muy necesaria para todos ellos.<br><br><br><br><br><br><br><br><br><br><br><br><br><br><br><br><br><br><br><br><br><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>AUSENCIO RIVERA\/VOCESVER.COM\/NOTICIASVeracruz,Ver,. a 29 de Julio 2023.-El presidente de la Casa del del Discapacitado Veracruzano A.C Ignacio Ayala Fararoni manifest\u00f3<\/p>\n","protected":false},"author":2,"featured_media":40192,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[2],"tags":[],"class_list":["post-40182","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infogral"],"_links":{"self":[{"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/posts\/40182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/comments?post=40182"}],"version-history":[{"count":4,"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/posts\/40182\/revisions"}],"predecessor-version":[{"id":40194,"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/posts\/40182\/revisions\/40194"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/media\/40192"}],"wp:attachment":[{"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/media?parent=40182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/categories?post=40182"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/tags?post=40182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}