{"id":39942,"date":"2023-07-15T00:25:26","date_gmt":"2023-07-15T00:25:26","guid":{"rendered":"http:\/\/vocesver.com\/noticias\/?p=39942"},"modified":"2023-07-15T00:28:02","modified_gmt":"2023-07-15T00:28:02","slug":"participaran-casi-400-competidores-en-triatlon-fuga-de-isla-este-domingo","status":"publish","type":"post","link":"http:\/\/vocesver.com\/noticias\/participaran-casi-400-competidores-en-triatlon-fuga-de-isla-este-domingo\/","title":{"rendered":"*Participar\u00e1n casi 400 competidores en Triatl\u00f3n Fuga de Isla, este domingo*"},"content":{"rendered":"\n<p>*59% son triatletas femeniles y 41% triatletas varoniles, informa el comit\u00e9 organizador<br><br>*Entrega de kits ser\u00e1 este s\u00e1bado 15 de julio de 10:00 a 15:30 horas en el hotel Hampton by Hilton<br><br>REDACCI\u00d3N\/VOCESVER.COM\/NOTICIAS<br><br>(Boca del R\u00edo, Ver, a 14 de julio de 2023).\u2013 Con 380 competidores se realizar\u00e1 la edici\u00f3n #11 del Triatl\u00f3n Fuga de Isla, este domingo 16 de julio a partir de las 05:45 horas, informa el director general, Francisco Res\u00e9ndiz Guevara.<br><br>En en el municipio Boca del R\u00edo se realizar\u00e1 el Triatl\u00f3n Fuga de Isla, organizado por Bike &amp; Run y Experiencia Deportiva; teniendo como escenario el boulevard Manuel \u00c1vila Camacho.<br><br>\u201cParticipar\u00e1n 380 competidores, empezaremos a las 05:45 horas con la modalidad de Medias Distancias, la nataci\u00f3n, los ol\u00edmpicos saldr\u00e1n a las 07:10 horas y los de categor\u00eda sprint arrancar\u00e1n a las 08:15 horas.<br><br>La ruta de ciclismo comprende desde la glorieta de Las Am\u00e9ricas hasta el Hotel Lois, no se va a entrar al municipio de Veracruz porque todav\u00eda hay gradas y no deseamos haya alg\u00fan percance.<br><br>La nataci\u00f3n ser\u00e1 en Playa Pelicano, junto al hotel Camino Real y la carrera ser\u00e1 desde el hotel Camino Real hacia Ruiz Cortines, un circuito de 7 kil\u00f3metros para Medias Distancias en donde se brindar\u00e1 hidrataci\u00f3n con tres puntos de ida y tres de regreso; habr\u00e1 tres puntos de hidrataci\u00f3n de cuerpo: uno a la altura del hotel Punta Azul, otro por el hotel City Express y otro por la concesionaria de la Porsche.<br><br>Agreg\u00f3.<br><br>Tenemos una buena expectativa del evento, en esta edici\u00f3n #11 del Triatl\u00f3n Fuga de Isla en donde participar\u00e1 41% triatletas varoniles y 59% triatletas femeniles, dijo finalmente el director general, Francisco Res\u00e9ndiz Guevara.<br><br>Tendremos modalidades de sprint individual y de medias distancias podr\u00e1n competir en forma individual o en relevos, estamos casi listos para desarrollar el triatl\u00f3n y nos visiten destacados exponentes estatales, nacionales e internacionales\u201d, dijo Res\u00e9ndiz Guevara.<br><br>Este s\u00e1bado 15 de julio se realizar\u00e1 la entrega de kits, a los participantes, en la Expo que estar\u00e1 ubicada en el Hotel Hampton by Hilton, en horario de 10:00 a 15:30 horas.<br><br>Para mayores informes, el comit\u00e9 organizador invita a consultar la web site: www.bike-and-run.com y\/o a la l\u00ednea telef\u00f3nica 2299239122. Las redes sociales est\u00e1n disponibles en Facebook e Instagram: bikeandrunveracruz<br><br><br><br><br><br><br><br><br><br><br><br><br><br><br><br><br><br><br><br><br><br><br><br><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>*59% son triatletas femeniles y 41% triatletas varoniles, informa el comit\u00e9 organizador *Entrega de kits ser\u00e1 este s\u00e1bado 15 de<\/p>\n","protected":false},"author":2,"featured_media":39950,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[2],"tags":[],"class_list":["post-39942","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infogral"],"_links":{"self":[{"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/posts\/39942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/comments?post=39942"}],"version-history":[{"count":2,"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/posts\/39942\/revisions"}],"predecessor-version":[{"id":39949,"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/posts\/39942\/revisions\/39949"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/media\/39950"}],"wp:attachment":[{"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/media?parent=39942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/categories?post=39942"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/tags?post=39942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}