{"id":37936,"date":"2022-11-15T22:14:08","date_gmt":"2022-11-15T22:14:08","guid":{"rendered":"http:\/\/vocesver.com\/noticias\/?p=37936"},"modified":"2022-11-15T22:30:48","modified_gmt":"2022-11-15T22:30:48","slug":"10-delegados-de-morena-se-pronuncian-a-favor-de-la-reforma-electoral-de-amlo","status":"publish","type":"post","link":"http:\/\/vocesver.com\/noticias\/10-delegados-de-morena-se-pronuncian-a-favor-de-la-reforma-electoral-de-amlo\/","title":{"rendered":"10 DELEGADOS DE MORENA SE PRONUNCIAN A FAVOR DE LA REFORMA ELECTORAL DE AMLO."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Dieron conferencia de medios en c\u00e9ntrico caf\u00e9 del Puerto jarocho.<br>Los delegados estuvieron encabezados por Maritza Cantarell delegada del distrito 4 de Veracruz.<br>Con esta reforma se ahorrar\u00e1n 24 mdp anuales que se canalizar\u00e1n a programas sociales.<br>AUSENCIO RIVERA\/VOCESVER.COM\/NOTICIAS<br><br>Veracruz,Ver.- a 15 de Noviembre 2022.- Por lo menos diez delegados distritales de Morena del municipio de Veracruz  se pronunciar\u00f3n a favor de la reforma electoral que propone el presidente de M\u00e9xico Andr\u00e9s Manuel Lop\u00e9z Obrador por  considerar que traer\u00e1  importantes beneficios para el pueblo de M\u00e9xico.<br>Al respecto Maritza Cantarell delegada del Distrito 4 en conferencia de medios dijo que la reforma busca mejorar al sistema electoral del INE, en ning\u00fan momento se busca desaprerecerlo,<br>Acompa\u00f1ada de  los tambi\u00e9n delegados Soraya Villas\u00eds, Esa\u00fa Hern\u00e1ndez,Yadira Tapia, Maricela Ponce,Diana P\u00e9rez,Enrique Nolasco,Manuel Rogel y Jos\u00e9 P\u00e9rez destac\u00f3 <br> que entre los beneficios se encuentran el de reducir el n\u00famero de diputados federales, de 500 a 300 y de senadores de 128 a 96 ,los consejeros, consejeras y los magistrados van a ser electos a trav\u00e9s del voto del pueblo. Ya no habr\u00e1 m\u00e1s imposiciones apunt\u00f3.<br>Indic\u00f3 que con  esta reforma el  Instituto Nacional Electoral y de Consulta(INEC) se ahorr\u00e1 24 mil millones de pesos anuales que se utilizar\u00e1n para incentivar los programas sociales en beneficio del pueblo.<br>Por su parte Soraya  Villas\u00eds reconoci\u00f3 que debido a estos y muchos m\u00e1s beneficios que vienen con esta reforma  para la ciudadan\u00eda es por ello que la oposici\u00f3n est\u00e1 en contra \u00abporque la mayor\u00eda de estos est\u00e1n acostumbrados al \u00abdedazo\u00bby a otras pr\u00e1cticas corruptas\u00bb.<br>Ojal\u00e1 que as\u00ed como se realiz\u00f3 la marcha en defensa del INE, as\u00ed se ejerciera la democracia.<br>Puntualizo  que es por ello que apoyan la reforma electoral  y est\u00e1n seguros que ser\u00e1 aprobada en la C\u00e1mara de Diputados. <br>Los delegados morenistas hicieron un llamado de reflexi\u00f3n a quienes se oponen a esta reforma, al tiempo que asegurar\u00f3n que si la oposici\u00f3n se opone es porque no les conviene que se les quiten los privilegios que han gozado desde hace muchos a\u00f1os.<br><br><br><br><br><br><br><br><br><br><br><br><br><br><br><br><br><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dieron conferencia de medios en c\u00e9ntrico caf\u00e9 del Puerto jarocho.Los delegados estuvieron encabezados por Maritza Cantarell delegada del distrito 4<\/p>\n","protected":false},"author":2,"featured_media":37945,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[2],"tags":[],"class_list":["post-37936","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infogral"],"_links":{"self":[{"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/posts\/37936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/comments?post=37936"}],"version-history":[{"count":3,"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/posts\/37936\/revisions"}],"predecessor-version":[{"id":37947,"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/posts\/37936\/revisions\/37947"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/media\/37945"}],"wp:attachment":[{"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/media?parent=37936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/categories?post=37936"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/vocesver.com\/noticias\/wp-json\/wp\/v2\/tags?post=37936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}